{"id":36026,"date":"2024-06-08T01:43:10","date_gmt":"2024-06-08T01:43:10","guid":{"rendered":"https:\/\/iahp.org\/matthew-success-story\/"},"modified":"2024-07-05T19:24:05","modified_gmt":"2024-07-05T19:24:05","slug":"matthew-success-story","status":"publish","type":"post","link":"https:\/\/iahp.org\/es\/matthew-success-story\/","title":{"rendered":"Diagn\u00f3stico: Retraso Global del Desarrollo, Deficiencia Mental y Autismo."},"content":{"rendered":"<h1><strong>\u00bfPodr\u00eda Matthew alguna vez tener una vida normal?<\/strong><\/h1>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-35942\" src=\"https:\/\/iahp.org\/wp-content\/uploads\/2024\/06\/matthew_ss_01-300x225.png\" alt=\"\" width=\"600\" height=\"450\" srcset=\"https:\/\/iahp.org\/wp-content\/uploads\/2024\/06\/matthew_ss_01-300x225.png 300w, https:\/\/iahp.org\/wp-content\/uploads\/2024\/06\/matthew_ss_01.png 515w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n<h2><strong>Nuestra pesadilla comenz\u00f3 en la consulta del especialista.<\/strong><\/h2>\n<p><em>\u00abMatthew tuvo un comienzo horrendo en la vida a\u00fan en el \u00fatero y debido a diversas complicaciones fue entregado mediante ces\u00e1rea a las 33 semanas junto a su hermano gemelo, Simon. <\/em><em>Permanecieron en la unidad neonatal durante 7 semanas.<\/em><\/p>\n<p><em>Matthew, como beb\u00e9, tard\u00f3 en alcanzar sus hitos del desarrollo. No camin\u00f3 hasta los 18 meses de edad, hablaba muy pocas palabras y babeaba. No me di cuenta de que Matthew ten\u00eda un problema hasta que lo llev\u00e9 a la guarder\u00eda a la edad de dos a\u00f1os y medio y comenc\u00e9, como la mayor\u00eda de las madres, a compararlo con otros ni\u00f1os de la misma edad.\u00bb<\/em><\/p>\n<h2><strong><em>\u00abMe di cuenta de lo diferente que era.\u00bb<\/em><\/strong><\/h2>\n<p><em>\u00abInmediatamente hice una cita con un pediatra del desarrollo y recib\u00ed el devastador diagn\u00f3stico de Retraso Global del Desarrollo. En ese momento supe que todas las posibilidades de que Matthew llevara una vida normal hab\u00edan desaparecido.\u00bb<\/em><\/p>\n<h2><strong><em>\u00abLlor\u00e9 todo el camino a casa.\u00bb<\/em><\/strong><\/h2>\n<p><em>\u00abJam\u00e1s una para conceder la derrota, busqu\u00e9 por internet un posible tratamiento y me top\u00e9 con el sitio web de Los Institutos.\u00bb<\/em><\/p>\n<p><em>\u00abDe inmediato me inscrib\u00ed en el curso \u2018<strong>Qu\u00e9 hacer por su hijo con lesi\u00f3n cerebral<\/strong>\u2019 y supe que hab\u00eda encontrado el plan de tratamiento para combatir los problemas de Matthew.\u00bb<\/em><\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-35944\" src=\"https:\/\/iahp.org\/wp-content\/uploads\/2024\/06\/matthew_ss_02-300x154.png\" alt=\"\" width=\"651\" height=\"334\" srcset=\"https:\/\/iahp.org\/wp-content\/uploads\/2024\/06\/matthew_ss_02-300x154.png 300w, https:\/\/iahp.org\/wp-content\/uploads\/2024\/06\/matthew_ss_02.png 523w\" sizes=\"(max-width: 651px) 100vw, 651px\" \/><\/p>\n<p><em>\u00abLo m\u00e1s importante que aprend\u00ed al hacer el curso fue que el cerebro, con suficiente estimulaci\u00f3n, realmente pod\u00eda cambiar y, lo m\u00e1s importante, crecer. Esta fue una gran revelaci\u00f3n, ya que iba en contra de todo lo que nos hab\u00edan dicho sobre el cerebro. La plasticidad cerebral estaba prosperando en Los Institutos.\u00bb<\/em><\/p>\n<p>Cuando la madre comenz\u00f3 un programa basado en lo que hab\u00eda aprendido en el curso, Matthew hablaba en palabras sueltas, pod\u00eda caminar pero prefer\u00eda que lo llevaran en brazos, su desarrollo general era del 40% de lo que deber\u00eda haber sido.<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-35946\" src=\"https:\/\/iahp.org\/wp-content\/uploads\/2024\/06\/matthew_ss_03-300x261.png\" alt=\"\" width=\"500\" height=\"435\" srcset=\"https:\/\/iahp.org\/wp-content\/uploads\/2024\/06\/matthew_ss_03-300x261.png 300w, https:\/\/iahp.org\/wp-content\/uploads\/2024\/06\/matthew_ss_03.png 514w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>Para su primera cita en Los Institutos, a la edad de cuatro a\u00f1os, Matthew ya hab\u00eda comenzado a hablar en oraciones, pod\u00eda correr 100 metros sin parar y su salud hab\u00eda mejorado.<\/p>\n<h2><strong>Su lenguaje explot\u00f3.<\/strong><\/h2>\n<p>Seis meses despu\u00e9s, Matthew estaba siguiendo instrucciones de m\u00faltiples pasos y le\u00eda mucho mejor que sus compa\u00f1eros. Su lenguaje hab\u00eda explotado, pasando de 100 palabras a m\u00e1s de mil, incluyendo frases largas y contar historias. Corr\u00eda \u00bd milla sin parar cada d\u00eda y hac\u00eda braquiaci\u00f3n de forma independiente en una escalera horizontal. Hab\u00eda estado en perfecta salud durante seis meses.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-35948\" src=\"https:\/\/iahp.org\/wp-content\/uploads\/2024\/06\/matthew_ss_04-222x300.png\" alt=\"\" width=\"500\" height=\"676\" srcset=\"https:\/\/iahp.org\/wp-content\/uploads\/2024\/06\/matthew_ss_04-222x300.png 222w, https:\/\/iahp.org\/wp-content\/uploads\/2024\/06\/matthew_ss_04.png 507w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>Antes de su sexto cumplea\u00f1os, Matthew estaba leyendo libros de la biblioteca; entendiendo \u00abtodo\u00bb; desde apenas unas pocas palabras de habla hace dos a\u00f1os, ahora ten\u00eda el habla conversacional de un ni\u00f1o de tres a\u00f1os y estaba expandiendo su vocabulario diariamente y corriendo un kil\u00f3metro sin parar.<\/p>\n<p>Gracias a la ense\u00f1anza de su madre, ha adquirido conocimientos generales sobre una amplia variedad de temas. Estaba muy por delante de sus compa\u00f1eros. Y lo mejor de todo, todos los d\u00edas Matthew, y su gemelo, Simon, disfrutaban de todo lo que hac\u00edan con su mejor maestra y entrenadora: su madre.<\/p>\n<h2><strong>El conocimiento general de Matthew ahora est\u00e1 por encima de sus compa\u00f1eros.<\/strong><\/h2>\n<p>Matthew y su gemelo recientemente celebraron su sexto cumplea\u00f1os. El habla de Matthew ahora es igual a su edad en contenido, mientras que su conocimiento general contin\u00faa expandi\u00e9ndose muy por encima de sus compa\u00f1eros. Matthew es una superestrella en la braquiaci\u00f3n: avanza, retrocede y gira en una escalera horizontal. Est\u00e1 corriendo 3 kil\u00f3metros, saltando a su nivel de edad y comenzando gimnasia. \u00a1Ahora no hay quien detenga a Matthew ni a Simon!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-35950\" src=\"https:\/\/iahp.org\/wp-content\/uploads\/2024\/06\/matthew_ss_05-225x300.png\" alt=\"\" width=\"500\" height=\"667\" srcset=\"https:\/\/iahp.org\/wp-content\/uploads\/2024\/06\/matthew_ss_05-225x300.png 225w, https:\/\/iahp.org\/wp-content\/uploads\/2024\/06\/matthew_ss_05.png 519w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>\u00abUnas palabras para todos los padres que reciben este diagn\u00f3stico: no se desesperen ni se desanimen por el diagn\u00f3stico de su hijo, s\u00e9 que esto es m\u00e1s f\u00e1cil decirlo que hacerlo. \u00a1P\u00f3nganse a trabajar! Inscr\u00edbanse en el curso <strong>\u2018Qu\u00e9 hacer por su hijo con lesi\u00f3n cerebral\u2019<\/strong> y comiencen la transformaci\u00f3n de su hijo o hija haciendo crecer su cerebro.\u00bb<\/p>\n<p>\u00abPerd\u00ed tanto tiempo en terapias convencionales (de lenguaje y ocupacionales) que no hicieron nada para mejorar los s\u00edntomas de Matthew. Nuestros hijos tienen un enorme potencial, y Los Institutos con su personal experto los ayudar\u00e1 y guiar\u00e1 para desbloquear este potencial.\u00bb<\/p>\n<h2><strong><em>\u00abNuestra pesadilla finalmente termin\u00f3 cuando cruc\u00e9 las puertas de Los Institutos.\u00bb<\/em><\/strong><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-35952\" src=\"https:\/\/iahp.org\/wp-content\/uploads\/2024\/06\/matthew_ss_06-300x225.png\" alt=\"\" width=\"540\" height=\"405\" srcset=\"https:\/\/iahp.org\/wp-content\/uploads\/2024\/06\/matthew_ss_06-300x225.png 300w, https:\/\/iahp.org\/wp-content\/uploads\/2024\/06\/matthew_ss_06.png 518w\" sizes=\"(max-width: 540px) 100vw, 540px\" \/><\/p>\n<p><em>\u00abLa pesadilla pudo haber comenzado en la consulta del especialista, pero finalmente termin\u00f3 cuando cruc\u00e9 las puertas de Los Institutos y supe que hab\u00eda encontrado la respuesta a las dificultades de desarrollo de Matthew. La vida de Matthew, que alguna vez parec\u00eda tan sombr\u00eda, se ha vuelto cada vez m\u00e1s prometedora.\u00bb<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-35954\" src=\"https:\/\/iahp.org\/wp-content\/uploads\/2024\/06\/matthew_ss_07-242x300.png\" alt=\"\" width=\"539\" height=\"668\" srcset=\"https:\/\/iahp.org\/wp-content\/uploads\/2024\/06\/matthew_ss_07-242x300.png 242w, https:\/\/iahp.org\/wp-content\/uploads\/2024\/06\/matthew_ss_07.png 517w\" sizes=\"(max-width: 539px) 100vw, 539px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfPodr\u00eda Matthew alguna vez tener una vida normal? Nuestra pesadilla comenz\u00f3 en la consulta del especialista. \u00abMatthew tuvo un comienzo<\/p>\n","protected":false},"author":11,"featured_media":35955,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[121,909],"tags":[],"post_topic":[],"class_list":["post-36026","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-the-news","category-sin-categorizar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Diagn\u00f3stico: Retraso Global del Desarrollo, Deficiencia Mental y Autismo. - Institutes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/iahp.org\/es\/matthew-success-story\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diagn\u00f3stico: Retraso Global del Desarrollo, Deficiencia Mental y Autismo. - Institutes\" \/>\n<meta property=\"og:description\" content=\"\u00bfPodr\u00eda Matthew alguna vez tener una vida normal? Nuestra pesadilla comenz\u00f3 en la consulta del especialista. \u00abMatthew tuvo un comienzo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/iahp.org\/es\/matthew-success-story\/\" \/>\n<meta property=\"og:site_name\" content=\"Institutes\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IAHPinternational\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-08T01:43:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-05T19:24:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/iahp.org\/wp-content\/uploads\/2024\/06\/matthew_ss_07.png\" \/>\n\t<meta property=\"og:image:width\" content=\"517\" \/>\n\t<meta property=\"og:image:height\" content=\"641\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"cpk4ce28e\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"cpk4ce28e\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/iahp.org\\\/es\\\/matthew-success-story\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/iahp.org\\\/es\\\/matthew-success-story\\\/\"},\"author\":{\"name\":\"cpk4ce28e\",\"@id\":\"https:\\\/\\\/iahp.org\\\/es\\\/#\\\/schema\\\/person\\\/4ce96692c950862253096801449b3280\"},\"headline\":\"Diagn\u00f3stico: Retraso Global del Desarrollo, Deficiencia Mental y Autismo.\",\"datePublished\":\"2024-06-08T01:43:10+00:00\",\"dateModified\":\"2024-07-05T19:24:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/iahp.org\\\/es\\\/matthew-success-story\\\/\"},\"wordCount\":827,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/iahp.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/iahp.org\\\/es\\\/matthew-success-story\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/iahp.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/matthew_ss_07.png\",\"articleSection\":[\"In the News\",\"Sin categorizar\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/iahp.org\\\/es\\\/matthew-success-story\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/iahp.org\\\/es\\\/matthew-success-story\\\/\",\"url\":\"https:\\\/\\\/iahp.org\\\/es\\\/matthew-success-story\\\/\",\"name\":\"Diagn\u00f3stico: Retraso Global del Desarrollo, Deficiencia Mental y Autismo. - Institutes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/iahp.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/iahp.org\\\/es\\\/matthew-success-story\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/iahp.org\\\/es\\\/matthew-success-story\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/iahp.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/matthew_ss_07.png\",\"datePublished\":\"2024-06-08T01:43:10+00:00\",\"dateModified\":\"2024-07-05T19:24:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/iahp.org\\\/es\\\/matthew-success-story\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/iahp.org\\\/es\\\/matthew-success-story\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/iahp.org\\\/es\\\/matthew-success-story\\\/#primaryimage\",\"url\":\"https:\\\/\\\/iahp.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/matthew_ss_07.png\",\"contentUrl\":\"https:\\\/\\\/iahp.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/matthew_ss_07.png\",\"width\":517,\"height\":641},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/iahp.org\\\/es\\\/matthew-success-story\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/iahp.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diagn\u00f3stico: Retraso Global del Desarrollo, Deficiencia Mental y Autismo.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/iahp.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/iahp.org\\\/es\\\/\",\"name\":\"Institutes\",\"description\":\"The Official Website\",\"publisher\":{\"@id\":\"https:\\\/\\\/iahp.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/iahp.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/iahp.org\\\/es\\\/#organization\",\"name\":\"The Institutes for the Achievement of Human Potential\",\"url\":\"https:\\\/\\\/iahp.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/iahp.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/iahp.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/iahp-logo-vector-bigger-text.svg\",\"contentUrl\":\"https:\\\/\\\/iahp.org\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/iahp-logo-vector-bigger-text.svg\",\"width\":280,\"height\":76,\"caption\":\"The Institutes for the Achievement of Human Potential\"},\"image\":{\"@id\":\"https:\\\/\\\/iahp.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/IAHPinternational\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/iahp.org\\\/es\\\/#\\\/schema\\\/person\\\/4ce96692c950862253096801449b3280\",\"name\":\"cpk4ce28e\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe44893632172bb14f4f574b8f086c364bcd217e237dba65f803f42bcc3dd0e1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe44893632172bb14f4f574b8f086c364bcd217e237dba65f803f42bcc3dd0e1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe44893632172bb14f4f574b8f086c364bcd217e237dba65f803f42bcc3dd0e1?s=96&d=mm&r=g\",\"caption\":\"cpk4ce28e\"},\"description\":\"Digital Media Coordinator Audiovisual Department Technician \u30a6\u30a7\u30d6\u9867\u554f(\u65e5\u672c)\",\"url\":\"https:\\\/\\\/iahp.org\\\/es\\\/author\\\/chris\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Diagn\u00f3stico: Retraso Global del Desarrollo, Deficiencia Mental y Autismo. - Institutes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/iahp.org\/es\/matthew-success-story\/","og_locale":"es_ES","og_type":"article","og_title":"Diagn\u00f3stico: Retraso Global del Desarrollo, Deficiencia Mental y Autismo. - Institutes","og_description":"\u00bfPodr\u00eda Matthew alguna vez tener una vida normal? Nuestra pesadilla comenz\u00f3 en la consulta del especialista. \u00abMatthew tuvo un comienzo","og_url":"https:\/\/iahp.org\/es\/matthew-success-story\/","og_site_name":"Institutes","article_publisher":"https:\/\/www.facebook.com\/IAHPinternational","article_published_time":"2024-06-08T01:43:10+00:00","article_modified_time":"2024-07-05T19:24:05+00:00","og_image":[{"width":517,"height":641,"url":"https:\/\/iahp.org\/wp-content\/uploads\/2024\/06\/matthew_ss_07.png","type":"image\/png"}],"author":"cpk4ce28e","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"cpk4ce28e","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/iahp.org\/es\/matthew-success-story\/#article","isPartOf":{"@id":"https:\/\/iahp.org\/es\/matthew-success-story\/"},"author":{"name":"cpk4ce28e","@id":"https:\/\/iahp.org\/es\/#\/schema\/person\/4ce96692c950862253096801449b3280"},"headline":"Diagn\u00f3stico: Retraso Global del Desarrollo, Deficiencia Mental y Autismo.","datePublished":"2024-06-08T01:43:10+00:00","dateModified":"2024-07-05T19:24:05+00:00","mainEntityOfPage":{"@id":"https:\/\/iahp.org\/es\/matthew-success-story\/"},"wordCount":827,"commentCount":0,"publisher":{"@id":"https:\/\/iahp.org\/es\/#organization"},"image":{"@id":"https:\/\/iahp.org\/es\/matthew-success-story\/#primaryimage"},"thumbnailUrl":"https:\/\/iahp.org\/wp-content\/uploads\/2024\/06\/matthew_ss_07.png","articleSection":["In the News","Sin categorizar"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/iahp.org\/es\/matthew-success-story\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/iahp.org\/es\/matthew-success-story\/","url":"https:\/\/iahp.org\/es\/matthew-success-story\/","name":"Diagn\u00f3stico: Retraso Global del Desarrollo, Deficiencia Mental y Autismo. - Institutes","isPartOf":{"@id":"https:\/\/iahp.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/iahp.org\/es\/matthew-success-story\/#primaryimage"},"image":{"@id":"https:\/\/iahp.org\/es\/matthew-success-story\/#primaryimage"},"thumbnailUrl":"https:\/\/iahp.org\/wp-content\/uploads\/2024\/06\/matthew_ss_07.png","datePublished":"2024-06-08T01:43:10+00:00","dateModified":"2024-07-05T19:24:05+00:00","breadcrumb":{"@id":"https:\/\/iahp.org\/es\/matthew-success-story\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/iahp.org\/es\/matthew-success-story\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/iahp.org\/es\/matthew-success-story\/#primaryimage","url":"https:\/\/iahp.org\/wp-content\/uploads\/2024\/06\/matthew_ss_07.png","contentUrl":"https:\/\/iahp.org\/wp-content\/uploads\/2024\/06\/matthew_ss_07.png","width":517,"height":641},{"@type":"BreadcrumbList","@id":"https:\/\/iahp.org\/es\/matthew-success-story\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/iahp.org\/es\/"},{"@type":"ListItem","position":2,"name":"Diagn\u00f3stico: Retraso Global del Desarrollo, Deficiencia Mental y Autismo."}]},{"@type":"WebSite","@id":"https:\/\/iahp.org\/es\/#website","url":"https:\/\/iahp.org\/es\/","name":"Institutes","description":"The Official Website","publisher":{"@id":"https:\/\/iahp.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/iahp.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/iahp.org\/es\/#organization","name":"The Institutes for the Achievement of Human Potential","url":"https:\/\/iahp.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/iahp.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/iahp.org\/wp-content\/uploads\/2021\/02\/iahp-logo-vector-bigger-text.svg","contentUrl":"https:\/\/iahp.org\/wp-content\/uploads\/2021\/02\/iahp-logo-vector-bigger-text.svg","width":280,"height":76,"caption":"The Institutes for the Achievement of Human Potential"},"image":{"@id":"https:\/\/iahp.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IAHPinternational"]},{"@type":"Person","@id":"https:\/\/iahp.org\/es\/#\/schema\/person\/4ce96692c950862253096801449b3280","name":"cpk4ce28e","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fe44893632172bb14f4f574b8f086c364bcd217e237dba65f803f42bcc3dd0e1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fe44893632172bb14f4f574b8f086c364bcd217e237dba65f803f42bcc3dd0e1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe44893632172bb14f4f574b8f086c364bcd217e237dba65f803f42bcc3dd0e1?s=96&d=mm&r=g","caption":"cpk4ce28e"},"description":"Digital Media Coordinator Audiovisual Department Technician \u30a6\u30a7\u30d6\u9867\u554f(\u65e5\u672c)","url":"https:\/\/iahp.org\/es\/author\/chris\/"}]}},"_links":{"self":[{"href":"https:\/\/iahp.org\/es\/wp-json\/wp\/v2\/posts\/36026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iahp.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iahp.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iahp.org\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/iahp.org\/es\/wp-json\/wp\/v2\/comments?post=36026"}],"version-history":[{"count":2,"href":"https:\/\/iahp.org\/es\/wp-json\/wp\/v2\/posts\/36026\/revisions"}],"predecessor-version":[{"id":36028,"href":"https:\/\/iahp.org\/es\/wp-json\/wp\/v2\/posts\/36026\/revisions\/36028"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iahp.org\/es\/wp-json\/wp\/v2\/media\/35955"}],"wp:attachment":[{"href":"https:\/\/iahp.org\/es\/wp-json\/wp\/v2\/media?parent=36026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iahp.org\/es\/wp-json\/wp\/v2\/categories?post=36026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iahp.org\/es\/wp-json\/wp\/v2\/tags?post=36026"},{"taxonomy":"post_topic","embeddable":true,"href":"https:\/\/iahp.org\/es\/wp-json\/wp\/v2\/post_topic?post=36026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}